{"id":6357,"date":"2023-01-04T20:11:16","date_gmt":"2023-01-04T19:11:16","guid":{"rendered":"https:\/\/www.regenbogen-hunteburg.de\/beta\/?p=6357"},"modified":"2023-01-04T20:11:18","modified_gmt":"2023-01-04T19:11:18","slug":"neu-im-team-4","status":"publish","type":"post","link":"https:\/\/www.regenbogen-hunteburg.de\/beta\/neu-im-team-4\/","title":{"rendered":"Neu im Team"},"content":{"rendered":"<p class=\"has-text-align-center\">Zum 01.01.2023 durften wir zwei neue Mitarbeiterinnen in unserem Team willkommen hei&szlig;en.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Frau Theresa Bu&szlig;mann <\/strong>ist als Fachkraft in der Marienk&auml;fergruppe t&auml;tig und <strong>Frau Christine Janwlecke<\/strong> unterst&uuml;tzt uns als Urlaubs- und Krankheitsvertretung. <\/p>\n\n\n\n<p class=\"has-text-align-center\">Wir freuen uns auf eine gute Zusammenarbeit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum 01.01.2023 durften wir zwei neue Mitarbeiterinnen in unserem Team willkommen hei&szlig;en. Frau Theresa Bu&szlig;mann ist als Fachkraft in der Marienk&auml;fergruppe t&auml;tig und Frau Christine Janwlecke unterst&uuml;tzt uns als Urlaubs- und Krankheitsvertretung. Wir freuen uns auf eine gute Zusammenarbeit!<\/p>\n","protected":false},"author":4,"featured_media":854,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-6357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personal"],"_links":{"self":[{"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/posts\/6357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/comments?post=6357"}],"version-history":[{"count":1,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/posts\/6357\/revisions"}],"predecessor-version":[{"id":6358,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/posts\/6357\/revisions\/6358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/media\/854"}],"wp:attachment":[{"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/media?parent=6357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/categories?post=6357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regenbogen-hunteburg.de\/beta\/wp-json\/wp\/v2\/tags?post=6357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}